{"id":48192,"date":"2025-09-26T04:21:26","date_gmt":"2025-09-26T07:21:26","guid":{"rendered":"https:\/\/tvtribunape.com.br\/index.php\/2025\/09\/26\/comlurb-inaugura-83o-ecoponto-e-ja-contabiliza-1-600-toneladas-diarias-a-menos-de-lixo-descartado-irregularmente-nas-ruas-da-cidade-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2025-09-26T04:21:26","modified_gmt":"2025-09-26T07:21:26","slug":"comlurb-inaugura-83o-ecoponto-e-ja-contabiliza-1-600-toneladas-diarias-a-menos-de-lixo-descartado-irregularmente-nas-ruas-da-cidade-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/tvtribunape.com.br\/index.php\/2025\/09\/26\/comlurb-inaugura-83o-ecoponto-e-ja-contabiliza-1-600-toneladas-diarias-a-menos-de-lixo-descartado-irregularmente-nas-ruas-da-cidade-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Comlurb inaugura 83\u00ba ecoponto e j\u00e1 contabiliza 1.600 toneladas di\u00e1rias a menos de lixo descartado irregularmente nas ruas da cidade &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div id=\"main\">\n<div class=\"wrapper-breadcrumbs\" wp_automatic_readability=\"26.025896414343\">\n<div class=\"image-post\" wp_automatic_readability=\"32\">\n                     O Ecoponto Pra\u00e7a da Paloma fica localizado no Complexo do Alem\u00e3o &#8211; Divulga\u00e7\u00e3o                  <\/div>\n<p>A Comlurb inaugurou, na manh\u00e3 desta quinta-feira (25\/9), o Ecoponto Pra\u00e7a da Paloma, na Rua Ant\u00f4nio Austreg\u00e9silo, 331, no Complexo do Alem\u00e3o. Com essa unidade, a Companhia soma 83 ecopontos lan\u00e7ados desde 2022. Essa pol\u00edtica p\u00fablica de combate \u00e0 forma\u00e7\u00e3o de pontos cr\u00edticos de descarte irregular na cidade j\u00e1 contabiliza 20% a menos de lixo jogado nas ruas, o correspondente a cerca de 1.600 toneladas di\u00e1rias de res\u00edduos que agora t\u00eam o destino correto.<\/p>\n<blockquote wp_automatic_readability=\"12\">\n<p>\u2013 Os pontos de descarte irregular de lixo, principalmente nas comunidades, t\u00eam sido combatidos por meio dessa pol\u00edtica p\u00fablica da Comlurb de instala\u00e7\u00e3o de ecopontos associada \u00e0 distribui\u00e7\u00e3o de cont\u00eaineres de grande porte, que j\u00e1 somam 12 mil. Os ecopontos n\u00e3o s\u00e3o assim meramente um local de descarte de lixo. Eles fazem parte de um planejamento estrat\u00e9gico da Companhia. \u00c9 a retirada de lixo irregular das ruas para a coleta \u2013 enfatizou o presidente da Comlurb, Jorge Arraes.<\/p>\n<\/blockquote>\n<p>A nova unidade conta com uma caixa compactadora para recebimento de lixo domiciliar e duas do tipo multiuso destinadas aos entulhos e bens inserv\u00edveis, como m\u00f3veis, colch\u00f5es e eletrodom\u00e9sticos sem uso, e galhos de \u00e1rvores. A inaugura\u00e7\u00e3o contou com o grupo Chegando de Surpresa, garis que usam m\u00fasica e dan\u00e7a em campanhas de conscientiza\u00e7\u00e3o para o descarte correto do lixo. Arraes lembra que a meta da Companhia \u00e9 chegar a 100 ecopontos at\u00e9 o fim do ano e a 22 mil cont\u00eaineres de grande porte instalados pela cidade. Al\u00e9m de ajudar na ordena\u00e7\u00e3o dos res\u00edduos, os ecopontos ainda evitam a prolifera\u00e7\u00e3o de vetores, levando mais qualidade de vida aos moradores e melhoria da sa\u00fade p\u00fablica.<\/p>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<div class=\"marcacao-category\">\n<article class=\"category-post\">\n<p>Categoria: <\/p>\n<\/article>\n<li>25 de setembro de 2025<\/li><\/div>\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: Comlurb Complexo do Alem\u00e3o descarte de lixo ecopontos<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Ecoponto Pra\u00e7a da Paloma fica localizado no Complexo do Alem\u00e3o &#8211; Divulga\u00e7\u00e3o A Comlurb<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48192","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48192"}],"version-history":[{"count":0,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48192\/revisions"}],"wp:attachment":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}