{"id":57026,"date":"2026-05-12T21:18:53","date_gmt":"2026-05-13T00:18:53","guid":{"rendered":"https:\/\/tvtribunape.com.br\/index.php\/2026\/05\/12\/lula-assina-mp-e-zera-taxa-das-blusinhas\/"},"modified":"2026-05-12T21:18:53","modified_gmt":"2026-05-13T00:18:53","slug":"lula-assina-mp-e-zera-taxa-das-blusinhas","status":"publish","type":"post","link":"https:\/\/tvtribunape.com.br\/index.php\/2026\/05\/12\/lula-assina-mp-e-zera-taxa-das-blusinhas\/","title":{"rendered":"Lula assina MP e zera &#8220;taxa das blusinhas&#8221;"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div wp_automatic_readability=\"60.99358974359\">\n<p><strong>O presidente Luiz In\u00e1cio Lula da Silva assinou, nesta ter\u00e7a-feira (12), uma Medida Provis\u00f3ria (MP) para acabar com a\u00a0cobran\u00e7a de 20% de Imposto de Importa\u00e7\u00e3o\u00a0sobre compras internacionais de at\u00e9 US$ 50, apelidada de\u00a0\u201ctaxa das blusinhas\u201d.<\/strong> \u00a0<\/p>\n<p>A Medida Provis\u00f3ria deve ser publicada em edi\u00e7\u00e3o extraordin\u00e1ria do Di\u00e1rio Oficial ainda hoje.\u00a0<\/p>\n<p>No ato de assinatura oficial, o secret\u00e1rio executivo do Minist\u00e9rio da Fazenda, Rog\u00e9rio Ceron, explicou que<strong> foi poss\u00edvel zerar o imposto ap\u00f3s tr\u00eas anos de combate ao contrabando e maior regulariza\u00e7\u00e3o do setor<\/strong>.\u00a0<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/12\/chega-ao-fim-luta-da-filha-de-roberto-justus-contra-o-cancer\/\">Chega ao fim luta da filha de Roberto Justus contra o c\u00e2ncer<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/12\/terremoto-atinge-teera-informa-midia-estatal-do-ira\/\">Terremoto atinge Teer\u00e3, informa m\u00eddia estatal do Ir\u00e3<\/a><\/strong><\/p>\n<blockquote wp_automatic_readability=\"10\">\n<p>\u201cO contrabando, que era uma marca presente nesse setor, foi eliminado. Agora, o setor regularizado vai poder usufruir dessa isen\u00e7\u00e3o sobre esses produtos\u201d, afirmou.<\/p>\n<\/blockquote>\n<p>Para o secret\u00e1rio, a decis\u00e3o vai<strong> beneficiar a popula\u00e7\u00e3o de baixa renda\u00a0que utiliza plataformas para adquirir produtos<\/strong>.\u00a0<\/p>\n<h2>\u201cN\u00e3o \u00e9 s\u00f3 blusinha\u201d<\/h2>\n<p>A ministra da Casa Civil, Miriam Belchior, destacou que, apesar do apelido, as compras internacionais desse valor s\u00e3o diversificadas, n\u00e3o apenas de roupas.<\/p>\n<p>\u201cN\u00e3o \u00e9 s\u00f3 roupa. H\u00e1 um conjunto de outros bens que s\u00e3o comprados, todos de valor pequeno\u201d, afirmou.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/12\/mp-de-santa-catarina-diz-que-cao-orelha-nao-foi-morto-por-adolescentes\/\">MP de Santa Catarina diz que c\u00e3o Orelha n\u00e3o foi morto por adolescentes<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/12\/moradores-sentiram-cheiro-de-gas-3-horas-antes-da-explosao-no-jaguare\/\">Moradores sentiram cheiro de g\u00e1s 3 horas antes da explos\u00e3o no Jaguar\u00e9<\/a><\/strong><\/p>\n<p>O ministro do Planejamento e Or\u00e7amento, Bruno Moretti, afirmou que<strong> zerar as taxas federais dessas compras melhora o perfil da nossa tributa\u00e7\u00e3o<\/strong>.<\/p>\n<p>\u201cOs n\u00fameros mostram que a maior parte das compras, de fato, \u00e9 de baixo valor. Est\u00e1 associado ao consumo popular\u201d.<\/p>\n<p>A chamada \u201ctaxa das blusinhas\u201d entrou em vigor em agosto de 2024, dentro do programa \u201cRemessa Conforme\u201d, criado para regulamentar o com\u00e9rcio eletr\u00f4nico internacional.<\/p>\n<p>Na pr\u00e1tica, o imposto era cobrado no momento da compra, para aumentar\u00a0a fiscaliza\u00e7\u00e3o e a redu\u00e7\u00e3o de fraudes.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews O presidente Luiz In\u00e1cio Lula da Silva assinou, nesta ter\u00e7a-feira (12), uma Medida<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-57026","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=57026"}],"version-history":[{"count":0,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57026\/revisions"}],"wp:attachment":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=57026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=57026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=57026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}