{"id":57035,"date":"2026-05-13T02:11:45","date_gmt":"2026-05-13T05:11:45","guid":{"rendered":"https:\/\/tvtribunape.com.br\/index.php\/2026\/05\/13\/flu-inter-e-cruzeiro-vencem-e-avancam-na-copa-do-brasil\/"},"modified":"2026-05-13T02:11:45","modified_gmt":"2026-05-13T05:11:45","slug":"flu-inter-e-cruzeiro-vencem-e-avancam-na-copa-do-brasil","status":"publish","type":"post","link":"https:\/\/tvtribunape.com.br\/index.php\/2026\/05\/13\/flu-inter-e-cruzeiro-vencem-e-avancam-na-copa-do-brasil\/","title":{"rendered":"Flu, Inter e Cruzeiro vencem e avan\u00e7am na Copa do Brasil"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"47.038054968288\">\n<p>A noite desta ter\u00e7a-feira (12) foi de classifica\u00e7\u00e3o de Fluminense, Internacional e Cruzeiro para as oitavas de final da Copa do Brasil. Diante de advers\u00e1rios de menor investimento, as tr\u00eas equipes da S\u00e9rie A do Campeonato Brasileiro venceram no tempo normal para avan\u00e7arem na competi\u00e7\u00e3o.<\/p>\n<p>Em partida disputada no est\u00e1dio do Maracan\u00e3, o Fluminense superou o Oper\u00e1rio por 2 a 1 para garantir sua vaga. O Tricolor das Laranjeiras chegou a abrir uma vantagem de dois gols com Savarino e Lucho Acosta. Por\u00e9m, na etapa final o time comandado pelo criticado t\u00e9cnico Luis Zubeld\u00eda desperdi\u00e7ou um p\u00eanalti com John Kennedy e viu a equipe de Ponta Grossa melhorar e descontar com o atacante Felipe Augusto.<\/p>\n<blockquote class=\"twitter-tweet\" wp_automatic_readability=\"11.67264573991\">\n<p dir=\"ltr\" lang=\"pt\" xml:lang=\"pt\">VEEEEEEEENNNNNCE O FLUMINEEEEEENNNSEEE! CLASSIFICADOS!<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/12\/chega-ao-fim-luta-da-filha-de-roberto-justus-contra-o-cancer\/\">Chega ao fim luta da filha de Roberto Justus contra o c\u00e2ncer<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/12\/carol-santiago-e-ouro-o-37o-podio-do-pais-no-internacional-de-berlim\/\">Carol Santiago \u00e9 ouro, o 37\u00ba p\u00f3dio do pa\u00eds no Internacional de Berlim<\/a><\/strong><\/p>\n<p>SAVARINO E LUCHO ACOSTA MARCAM, FLU VENCE O OPER\u00c1RIO NO MARACA E EST\u00c1 CLASSIFICADO PARA AS OITAVAS DE FINAL DA COPA DO BRASIL! VAAAMMMOS, TRICOLOR!\ud83c\udded\ud83c\uddfa\ud83c\udded\ud83c\uddfa\ud83c\udded\ud83c\uddfa\ud83c\udded\ud83c\uddfa <a href=\"https:\/\/t.co\/31flDoZBc0\">pic.twitter.com\/31flDoZBc0<\/a><\/p>\n<p>\u2014 Fluminense F.C. (@FluminenseFC) <a href=\"https:\/\/twitter.com\/FluminenseFC\/status\/2054388820619981140?ref_src=twsrc%5Etfw\">May 13, 2026<\/a><\/p>\n<\/blockquote>\n<p>Quem tamb\u00e9m n\u00e3o teve vida f\u00e1cil para se classificar foi o Cruzeiro, que derrotou o Goi\u00e1s por 1 a 0, em pleno est\u00e1dio do Mineir\u00e3o, para avan\u00e7ar. O \u00fanico gol da partida foi marcado aos 31 minutos do primeiro tempo pelo atacante Kaio Jorge em cobran\u00e7a de p\u00eanalti.<\/p>\n<blockquote class=\"twitter-tweet\" wp_automatic_readability=\"13.095693779904\">\n<p dir=\"ltr\" lang=\"pt\" xml:lang=\"pt\">\ud83d\udd58 Fim de jogo e \ud835\udde2 \ud835\uddd6\ud835\udde5\ud835\udde8\ud835\udded\ud835\uddd8\ud835\udddc\ud835\udde5\ud835\udde2 \ud835\uddd4\ud835\udde9\ud835\uddd4\ud835\udde1\ud835\uddd6\u0327\ud835\uddd4 \ud835\udde3\ud835\uddd4\ud835\udde5\ud835\uddd4 \ud835\uddd4\ud835\udde6 \ud835\udde2\ud835\udddc\ud835\udde7\ud835\uddd4\ud835\udde9\ud835\uddd4\ud835\udde6 \ud835\uddd7\ud835\uddd8 \ud835\uddd9\ud835\udddc\ud835\udde1\ud835\uddd4\ud835\udddf \ud835\uddd7\ud835\uddd4 \ud835\uddd6\ud835\udde2\ud835\udde3\ud835\uddd4 \ud835\uddd7\ud835\udde2 \ud835\uddd5\ud835\udde5\ud835\uddd4\ud835\udde6\ud835\udddc\ud835\udddf!!! \ud83e\udd8a<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/11\/br-feminino-palmeiras-goleia-atletico-mg-e-assume-vice-lideranca\/\">BR feminino: Palmeiras goleia Atl\u00e9tico-MG e assume vice-lideran\u00e7a<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/05\/11\/novas-fotos-do-itau-world-legend-chamam-atencao-nas-redes-e-cartao-vira-assunto-entre-clientes-de-alta-renda\/\">Novas fotos do Ita\u00fa World Legend chamam aten\u00e7\u00e3o nas redes e cart\u00e3o vira assunto entre clientes de alta renda<\/a><\/strong><\/p>\n<p>COM GOL DE KAIO JORGE, O CABULOSO VENCE O GOI\u00c1S E EST\u00c1 CLASSIFICADO PARA A PR\u00d3XIMA FASE! VAMOOOOOS! \ud83d\udc4a<\/p>\n<p>\ud83d\udd37 <a href=\"https:\/\/twitter.com\/hashtag\/CRUxGOI?src=hash&amp;ref_src=twsrc%5Etfw\">#CRUxGOI<\/a> | 1-0 | <a href=\"https:\/\/twitter.com\/hashtag\/ReiDeCopas?src=hash&amp;ref_src=twsrc%5Etfw\">#ReiDeCopas<\/a> <a href=\"https:\/\/t.co\/8xvsM15mAR\">pic.twitter.com\/8xvsM15mAR<\/a><\/p>\n<p>\u2014 Cruzeiro \ud83e\udd8a (@Cruzeiro) <a href=\"https:\/\/twitter.com\/Cruzeiro\/status\/2054388591971704843?ref_src=twsrc%5Etfw\">May 13, 2026<\/a><\/p>\n<\/blockquote>\n<p>O terceiro time classificado para as oitavas de final foi o Internacional. O Colorado avan\u00e7ou para a pr\u00f3xima fase da competi\u00e7\u00e3o ap\u00f3s um triunfo de 3 a 2 sobre o Athletic no Beira-Rio. Bernabei, Allex e Borr\u00e9 fizeram os gols do time de Paulo Pezzolano, enquanto Ian Luccas marcou duas vezes para os mineiros.<\/p>\n<blockquote class=\"twitter-tweet\" wp_automatic_readability=\"16.754137115839\">\n<p dir=\"ltr\" lang=\"pt\" xml:lang=\"pt\">\ud835\uddd6\ud835\udddf\ud835\udde8\ud835\uddd5\ud835\uddd8 \ud835\uddd7\ud835\udde2 \ud835\udde3\ud835\udde2\ud835\udde9\ud835\udde2 \ud835\udde9\ud835\uddd8\ud835\udde1\ud835\uddd6\ud835\uddd8 \ud835\uddd8 \ud835\udde6\ud835\uddd8 \ud835\uddd6\ud835\udddf\ud835\uddd4\ud835\udde6\ud835\udde6\ud835\udddc\ud835\uddd9\ud835\udddc\ud835\uddd6\ud835\uddd4! \u2764\ufe0f\ud83e\udd0d<\/p>\n<p>Com gols de Borr\u00e9, Allex e Bernabei, Inter volta a superar o Athletic-MG, desta vez por 3 a 2, e avan\u00e7a para as oitavas de final da Copa do Brasil! \u26bd\ud83c\udde6\ud83c\uddf9 <a href=\"https:\/\/twitter.com\/hashtag\/Isso%C3%89Inter?src=hash&amp;ref_src=twsrc%5Etfw\">#Isso\u00c9Inter<\/a><\/p>\n<p>VAMOS, COLORADO! \ud83d\udcaa\ud83d\udc4a <a href=\"https:\/\/t.co\/hjvp82287i\">pic.twitter.com\/hjvp82287i<\/a><\/p>\n<p>\u2014 Sport Club Internacional (@SCInternacional) <a href=\"https:\/\/twitter.com\/SCInternacional\/status\/2054357133110440431?ref_src=twsrc%5Etfw\">May 13, 2026<\/a><\/p>\n<\/blockquote>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A noite desta ter\u00e7a-feira (12) foi de classifica\u00e7\u00e3o de Fluminense, Internacional e Cruzeiro para as<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-57035","post","type-post","status-publish","format-standard","hentry","category-futebol"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=57035"}],"version-history":[{"count":0,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/57035\/revisions"}],"wp:attachment":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=57035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=57035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=57035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}