{"id":59565,"date":"2026-07-14T09:17:21","date_gmt":"2026-07-14T12:17:21","guid":{"rendered":"https:\/\/tvtribunape.com.br\/index.php\/2026\/07\/14\/onu-mulheres-oferece-formacao-digital-gratuita-saiba-como-participar\/"},"modified":"2026-07-14T09:17:21","modified_gmt":"2026-07-14T12:17:21","slug":"onu-mulheres-oferece-formacao-digital-gratuita-saiba-como-participar","status":"publish","type":"post","link":"https:\/\/tvtribunape.com.br\/index.php\/2026\/07\/14\/onu-mulheres-oferece-formacao-digital-gratuita-saiba-como-participar\/","title":{"rendered":"ONU Mulheres oferece forma\u00e7\u00e3o digital gratuita; saiba como participar"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div>\n<p><strong>A ONU Mulheres Brasil ir\u00e1 oferecer uma forma\u00e7\u00e3o digital gratuita a mulheres em dez capitais brasileiras. As inscri\u00e7\u00f5es est\u00e3o abertas e podem ser feitas at\u00e9 o dia 19 de julho.<\/strong><\/p>\n<p>A forma\u00e7\u00e3o Mulher + Tech: Conex\u00e3o para Novos Come\u00e7os inclui letramento digital e uso da tecnologia no dia a dia, seguran\u00e7a e bem-estar no ambiente digital, direito das mulheres, e empregabilidade e empreendedorismo. As aulas ser\u00e3o em formato h\u00edbrido, com atividades presenciais e virtuais.<\/p>\n<p>Al\u00e9m de ser gratuito, o programa oferece apoio \u00e0s participantes: <em>chip<\/em> com internet com validade de 12 meses, aux\u00edlio para deslocamento e alimenta\u00e7\u00e3o, estrutura de cuidado para crian\u00e7as durante encontros presenciais e, para quem concluir ao menos 75% da forma\u00e7\u00e3o, um aparelho celular ao final da jornada.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/como-uma-copa-america-moldou-a-scaloneta-e-transformou-lionel-messi\/\">Como uma Copa Am\u00e9rica moldou a \u201cScaloneta\u201d e transformou Lionel Messi<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/tragedia-no-ceara-mae-e-filha-morrem-em-grave-acidente-na-ce-362\/\">Trag\u00e9dia no Cear\u00e1, m\u00e3e e filha morrem em grave acidente na CE-362<\/a><\/strong><\/p>\n<h2>Quem pode participar?<\/h2>\n<p><strong>Podem participar mulheres em situa\u00e7\u00e3o de vulnerabilidade socioecon\u00f4mica \u2013\u00a0incluindo aquelas com baixa inclus\u00e3o digital, perif\u00e9ricas, em situa\u00e7\u00e3o de viol\u00eancia, migrantes e refugiadas, e aquelas com dificuldade de acesso a direitos e servi\u00e7os digitais<\/strong>.<\/p>\n<p>Em Bel\u00e9m, Manaus, Cuiab\u00e1, Curitiba, Recife e Rio de Janeiro, ser\u00e3o selecionadas 150 mulheres por cidade. Em Belo Horizonte, S\u00e3o Paulo, Boa Vista e Salvador, 100\u00a0por cidade.<\/p>\n<p><strong>A prioridade ser\u00e1 de mulheres que enfrentam maiores barreiras de acesso \u00e0 tecnologia, \u00e0 forma\u00e7\u00e3o e a oportunidades de desenvolvimento, considerando aspectos como renda e contexto social informados no momento da inscri\u00e7\u00e3o.<\/strong><\/p>\n<h2>Inscri\u00e7\u00f5es<\/h2>\n<p>O Mulher + Tech \u00e9 uma iniciativa da ONU Mulheres Brasil, financiada pela Claro e implementada pela Politize!. As inscri\u00e7\u00f5es devem ser feitas pela internet, neste <em>link<\/em>.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/taxa-da-prova-nacional-docente-pnd-deve-ser-paga-nesta-terca-feira\/\">Taxa da Prova Nacional Docente (PND) deve ser paga nesta ter\u00e7a-feira<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/esfera-lanca-promocao-com-ate-30-de-vantagem-nas-transferencias-para-o-all-accor-veja-como-funciona\/\">Esfera lan\u00e7a promo\u00e7\u00e3o com at\u00e9 30% de vantagem nas transfer\u00eancias para o ALL Accor; veja como funciona<\/a><\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews A ONU Mulheres Brasil ir\u00e1 oferecer uma forma\u00e7\u00e3o digital gratuita a mulheres em<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-59565","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59565"}],"version-history":[{"count":0,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59565\/revisions"}],"wp:attachment":[{"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvtribunape.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}